{"id":135,"count":2,"description":"","link":"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/","name":"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438","slug":"winch-handle-ru","taxonomy":"product_cat","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438 Archives - Merelinn<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438 Archives - Merelinn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/\" \/>\n<meta property=\"og:site_name\" content=\"Merelinn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/\",\"url\":\"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/\",\"name\":\"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438 Archives - Merelinn\",\"isPartOf\":{\"@id\":\"https:\/\/merelinn.com\/ru\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/#breadcrumb\"},\"inLanguage\":\"ru-RU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f\",\"item\":\"https:\/\/merelinn.com\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041c\u0430\u0433\u0430\u0437\u0438\u043d\",\"item\":\"https:\/\/merelinn.com\/ru\/?page_id=1559\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/merelinn.com\/ru\/#website\",\"url\":\"https:\/\/merelinn.com\/ru\/\",\"name\":\"Merelinn\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/merelinn.com\/ru\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438 Archives - Merelinn","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ru_RU","og_type":"article","og_title":"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438 Archives - Merelinn","og_url":"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/","og_site_name":"Merelinn","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/","url":"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/","name":"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438 Archives - Merelinn","isPartOf":{"@id":"https:\/\/merelinn.com\/ru\/#website"},"breadcrumb":{"@id":"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/#breadcrumb"},"inLanguage":"ru-RU"},{"@type":"BreadcrumbList","@id":"https:\/\/merelinn.com\/ru\/product-category\/winch-handle-ru\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","item":"https:\/\/merelinn.com\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041c\u0430\u0433\u0430\u0437\u0438\u043d","item":"https:\/\/merelinn.com\/ru\/?page_id=1559"},{"@type":"ListItem","position":3,"name":"\u0420\u0443\u0447\u043a\u0430 \u043b\u0435\u0431\u0451\u0434\u043a\u0438"}]},{"@type":"WebSite","@id":"https:\/\/merelinn.com\/ru\/#website","url":"https:\/\/merelinn.com\/ru\/","name":"Merelinn","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/merelinn.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"}]}},"_links":{"self":[{"href":"https:\/\/merelinn.com\/ru\/wp-json\/wp\/v2\/product_cat\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merelinn.com\/ru\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/merelinn.com\/ru\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/merelinn.com\/ru\/wp-json\/wp\/v2\/product?product_cat=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}