{"id":3157,"date":"2025-04-11T12:15:08","date_gmt":"2025-04-11T09:15:08","guid":{"rendered":"https:\/\/merelinn.com\/brands\/bmf\/deckfab\/"},"modified":"2025-04-23T17:17:11","modified_gmt":"2025-04-23T14:17:11","slug":"deckfab","status":"publish","type":"page","link":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/","title":{"rendered":"DeckFAB"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2260,"parent":3144,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[75,76],"tags":[],"class_list":["post-3157","page","type-page","status-publish","has-post-thumbnail","hentry","category-bmf-lv","category-brands-lv"],"acf":{"photo_gallery":{"brand_gallery":[[{"id":2506,"title":"3dec1044-af25-4260-b2c3-b7b5f78e9d77","caption":"","full_image_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77.jpg","thumbnail_image_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-150x150.jpg","large_srcset":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-1024x768.jpg 1024w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-300x225.jpg 300w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-768x576.jpg 768w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-1536x1152.jpg 1536w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-600x450.jpg 600w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77.jpg 1600w","medium_srcset":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-300x225.jpg 300w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-1024x768.jpg 1024w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-768x576.jpg 768w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-1536x1152.jpg 1536w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-600x450.jpg 600w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77.jpg 1600w","media_details":{"width":1600,"height":1200,"sizes":{"medium":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-300x225.jpg","width":300,"height":225,"mime-type":"image\/jpeg","filesize":14806,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-300x225.jpg"},"large":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-1024x768.jpg","width":1024,"height":768,"mime-type":"image\/jpeg","filesize":120587,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-1024x768.jpg"},"thumbnail":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5145,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-150x150.jpg"},"medium_large":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-768x576.jpg","width":768,"height":576,"mime-type":"image\/jpeg","filesize":77184,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-768x576.jpg"},"1536x1536":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-1536x1152.jpg","width":1536,"height":1152,"mime-type":"image\/jpeg","filesize":223859,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-1536x1152.jpg"},"woocommerce_thumbnail":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-300x300.jpg","width":300,"height":300,"mime-type":"image\/jpeg","filesize":19001,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-300x300.jpg"},"woocommerce_single":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-600x450.jpg","width":600,"height":450,"mime-type":"image\/jpeg","filesize":51657,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-600x450.jpg"},"woocommerce_gallery_thumbnail":{"file":"3dec1044-af25-4260-b2c3-b7b5f78e9d77-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":2529,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/3dec1044-af25-4260-b2c3-b7b5f78e9d77-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":2512,"title":"7b59f56c-2d66-4683-bf5f-4215b85747cb","caption":"","full_image_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb.jpg","thumbnail_image_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-150x150.jpg","large_srcset":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-768x1024.jpg 768w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-225x300.jpg 225w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-1152x1536.jpg 1152w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-600x800.jpg 600w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb.jpg 1200w","medium_srcset":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-225x300.jpg 225w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-768x1024.jpg 768w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-1152x1536.jpg 1152w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-600x800.jpg 600w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb.jpg 1200w","media_details":{"width":1200,"height":1600,"sizes":{"medium":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":16583,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-225x300.jpg"},"large":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-768x1024.jpg","width":768,"height":1024,"mime-type":"image\/jpeg","filesize":144894,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-768x1024.jpg"},"thumbnail":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5739,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-150x150.jpg"},"medium_large":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-768x1024.jpg","width":768,"height":1024,"mime-type":"image\/jpeg","filesize":144894,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-768x1024.jpg"},"1536x1536":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-1152x1536.jpg","width":1152,"height":1536,"mime-type":"image\/jpeg","filesize":272888,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-1152x1536.jpg"},"woocommerce_thumbnail":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-300x300.jpg","width":300,"height":300,"mime-type":"image\/jpeg","filesize":21519,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-300x300.jpg"},"woocommerce_single":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-600x800.jpg","width":600,"height":800,"mime-type":"image\/jpeg","filesize":94084,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-600x800.jpg"},"woocommerce_gallery_thumbnail":{"file":"7b59f56c-2d66-4683-bf5f-4215b85747cb-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":2778,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/7b59f56c-2d66-4683-bf5f-4215b85747cb-100x100.jpg"}}},"alt_text":"","url":"","target":""},{"id":2518,"title":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88","caption":"","full_image_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88.jpg","thumbnail_image_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-150x150.jpg","large_srcset":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-768x1024.jpg 768w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-225x300.jpg 225w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-1152x1536.jpg 1152w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-600x800.jpg 600w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88.jpg 1200w","medium_srcset":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-225x300.jpg 225w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-768x1024.jpg 768w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-1152x1536.jpg 1152w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-600x800.jpg 600w, https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88.jpg 1200w","media_details":{"width":1200,"height":1600,"sizes":{"medium":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-225x300.jpg","width":225,"height":300,"mime-type":"image\/jpeg","filesize":13244,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-225x300.jpg"},"large":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-768x1024.jpg","width":768,"height":1024,"mime-type":"image\/jpeg","filesize":115746,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-768x1024.jpg"},"thumbnail":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4823,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-150x150.jpg"},"medium_large":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-768x1024.jpg","width":768,"height":1024,"mime-type":"image\/jpeg","filesize":115746,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-768x1024.jpg"},"1536x1536":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-1152x1536.jpg","width":1152,"height":1536,"mime-type":"image\/jpeg","filesize":224699,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-1152x1536.jpg"},"woocommerce_thumbnail":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-300x300.jpg","width":300,"height":300,"mime-type":"image\/jpeg","filesize":17886,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-300x300.jpg"},"woocommerce_single":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-600x800.jpg","width":600,"height":800,"mime-type":"image\/jpeg","filesize":75031,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-600x800.jpg"},"woocommerce_gallery_thumbnail":{"file":"9d0f1aa3-6732-4653-b3d7-6fef97c39a88-100x100.jpg","width":100,"height":100,"mime-type":"image\/jpeg","filesize":2397,"source_url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/9d0f1aa3-6732-4653-b3d7-6fef97c39a88-100x100.jpg"}}},"alt_text":"","url":"","target":""}]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DeckFAB - Merelinn<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"lv_LV\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DeckFAB - Merelinn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/\" \/>\n<meta property=\"og:site_name\" content=\"Merelinn\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T14:17:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/\",\"url\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/\",\"name\":\"DeckFAB - Merelinn\",\"isPartOf\":{\"@id\":\"https:\/\/merelinn.com\/lv\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg\",\"datePublished\":\"2025-04-11T09:15:08+00:00\",\"dateModified\":\"2025-04-23T14:17:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#breadcrumb\"},\"inLanguage\":\"lv-LV\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lv-LV\",\"@id\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#primaryimage\",\"url\":\"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg\",\"contentUrl\":\"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"M\u0101jas lapa\",\"item\":\"https:\/\/merelinn.com\/lv\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Z\u012bmoli\",\"item\":\"https:\/\/merelinn.com\/lv\/brands\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beautiful Marine Floors\",\"item\":\"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"DeckFAB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/merelinn.com\/lv\/#website\",\"url\":\"https:\/\/merelinn.com\/lv\/\",\"name\":\"Merelinn\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/merelinn.com\/lv\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lv-LV\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DeckFAB - Merelinn","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"lv_LV","og_type":"article","og_title":"DeckFAB - Merelinn","og_url":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/","og_site_name":"Merelinn","article_modified_time":"2025-04-23T14:17:11+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/","url":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/","name":"DeckFAB - Merelinn","isPartOf":{"@id":"https:\/\/merelinn.com\/lv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#primaryimage"},"image":{"@id":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#primaryimage"},"thumbnailUrl":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg","datePublished":"2025-04-11T09:15:08+00:00","dateModified":"2025-04-23T14:17:11+00:00","breadcrumb":{"@id":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#breadcrumb"},"inLanguage":"lv-LV","potentialAction":[{"@type":"ReadAction","target":["https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/"]}]},{"@type":"ImageObject","inLanguage":"lv-LV","@id":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#primaryimage","url":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg","contentUrl":"https:\/\/merelinn.com\/wp-content\/uploads\/2025\/04\/Boats1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/deckfab\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"M\u0101jas lapa","item":"https:\/\/merelinn.com\/lv\/"},{"@type":"ListItem","position":2,"name":"Z\u012bmoli","item":"https:\/\/merelinn.com\/lv\/brands\/"},{"@type":"ListItem","position":3,"name":"Beautiful Marine Floors","item":"https:\/\/merelinn.com\/lv\/zimoli\/bmf\/"},{"@type":"ListItem","position":4,"name":"DeckFAB"}]},{"@type":"WebSite","@id":"https:\/\/merelinn.com\/lv\/#website","url":"https:\/\/merelinn.com\/lv\/","name":"Merelinn","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/merelinn.com\/lv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lv-LV"}]}},"_links":{"self":[{"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/pages\/3157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/comments?post=3157"}],"version-history":[{"count":1,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/pages\/3157\/revisions"}],"predecessor-version":[{"id":4030,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/pages\/3157\/revisions\/4030"}],"up":[{"embeddable":true,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/pages\/3144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/media\/2260"}],"wp:attachment":[{"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/media?parent=3157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/categories?post=3157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/merelinn.com\/lv\/wp-json\/wp\/v2\/tags?post=3157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}